{"id":3167,"date":"2017-03-02T08:28:11","date_gmt":"2017-03-02T07:28:11","guid":{"rendered":"https:\/\/fima.ub.edu\/edl\/la-autopublicacion\/"},"modified":"2026-03-04T14:16:27","modified_gmt":"2026-03-04T13:16:27","slug":"la-autopublicacion","status":"publish","type":"post","link":"https:\/\/fima.ub.edu\/edl\/la-autopublicacion\/","title":{"rendered":"La autopublicaci\u00f3n"},"content":{"rendered":"<p class=\"rtejustify\"><span style=\"font-size:14px;\"><a href=\"http:\/\/www.elprofesionaldelainformacion.com\/libros\/autopublicar.html\" target=\"_blank\"><img decoding=\"async\" class=\"drupal-import-img\" alt=\"\" src=\"\/edl\/wp-content\/inici_blog_EdL\/2017\/ressenyes\/coberta_autopublicar.jpg\" style=\"width: 150px; height: 223px; border-width: 1px; border-style: solid; margin-left: 5px; margin-right: 5px; float: left;\" \/><\/a>Mangas-Vega, Almudena. <em>Autopublicar: los nuevos circuitos para autores e investigadores.<\/em> Barcelona: UOC, 2016. 109 p. (El profesional de la informaci\u00f3n; 34). ISBN 978-84-9116-586-6. 12 \u20ac.<\/span><\/p>\n<p class=\"rtejustify\"><span style=\"font-size: 14px;\">El fen\u00f3meno la autopublicaci\u00f3n no es tal fen\u00f3meno si nos remitimos al libro <\/span><em style=\"font-size: 14px;\">Autopublicar: los nuevos circuitos para autores e investigadores,<\/em><span style=\"font-size: 14px;\"> de la autora Almudena Mangas-Vega. El libro publicado por la Editorial UOC de la serie El profesional de la informaci\u00f3n, nos muestra las posibilidades que ofrece la publicaci\u00f3n hoy en d\u00eda.<\/span><\/p>\n<p><!--break--><\/p>\n<p class=\"rtejustify\"><span style=\"font-size:14px;\">En el libro se hace un viaje a trav\u00e9s del tiempo, donde se analiza la historia de la autopublicaci\u00f3n, donde relata la situaci\u00f3n de diferentes autores con distintas especialidades que fueron rechazados por editoriales y emprendieron el camino de la autopublicaci\u00f3n ellos mismos. Toda esta l\u00ednea de tiempo arranca en 1759.<\/span><\/p>\n<p class=\"rtejustify\"><span style=\"font-size:14px;\">Cabe tener presente que la autopublicaci\u00f3n hace unos a\u00f1os, me atrever\u00eda a decir que no hace muchos, implicaba para el autor la gesti\u00f3n completa de todo su proceso editorial. Es decir, que adem\u00e1s de escribir su libro, ten\u00eda que realizar todas las tareas involucradas en el proceso de publicaci\u00f3n de un libro. Estas tareas eran las de edici\u00f3n, producci\u00f3n, gesti\u00f3n y promoci\u00f3n de su obra con el fin de poder obtener un beneficio con los escritos de su obra.<\/span><\/p>\n<p class=\"rtejustify\"><span style=\"font-size:14px;\">Tambi\u00e9n es verdad, tal y como se muestra dentro del libro, que han existido autores que han publicado sus propias obras. Muchas veces han realizado estas acciones porque ha sido su decisi\u00f3n o bien porque simplemente les gustaba.<\/span><\/p>\n<p class=\"rtejustify\"><span style=\"font-size:14px;\">Pasa el tiempo y aparecen los primeros formatos de libros digitales de la mano de Amazon, y con ello aparece un modelo de negocio diferente. Se reducen los costes de publicaci\u00f3n, ya que el papel en un principio desaparece, pero vuelve a aparecer con las impresiones sobre pedido.<\/span><\/p>\n<p class=\"rtejustify\"><span style=\"font-size:14px;\">Por otro lado, la autora hace \u00e9nfasis especial tambi\u00e9n en el mundo acad\u00e9mico, el mundo de la investigaci\u00f3n. La falta de controles a la hora de poder realizar trabajos autopublicados desde el mundo cient\u00edfico, hace que esta pr\u00e1ctica todav\u00eda no est\u00e9 muy expandida en el mundo acad\u00e9mico. Adem\u00e1s, influye el hecho de no tener validez para la propia carrera acad\u00e9mica. Sin embargo, la autora menciona una iniciativa a este respecto, donde hay vinculadas diversas instituciones y universidades.<\/span><\/p>\n<p class=\"rtejustify\"><span style=\"font-size:14px;\">Una vez identificados los diferentes actores dentro de la autopublicaci\u00f3n, podemos observar dentro del libro los diferentes pasos a seguir para poder autopublicar un libro. Desde la escritura del texto y edici\u00f3n del libro, el dise\u00f1o de la cubierta \u2013que siempre es recomendable que sea realizada por un dise\u00f1ador profesional\u2013, as\u00ed como la elecci\u00f3n del tipo de formato digital de la obra a publicar.<\/span><\/p>\n<p class=\"rtejustify\"><span style=\"font-size:14px;\">Tambi\u00e9n nos encontramos con otras cuestiones como la selecci\u00f3n de metadatos, un aspecto muy importante para \u00abser descubiertos\u00bb dentro de los buscadores de las diferentes plataformas digitales. Finalmente, otros aspectos a tener en cuenta y que la autora menciona son el establecimiento del precio, la promoci\u00f3n y la distribuci\u00f3n.<\/span><\/p>\n<p class=\"rtejustify\"><span style=\"font-size:14px;\">Para finalizar el libro, la autora nos muestra las diferentes plataformas existentes para poder autopublicar libros, donde se puede establecer un precio de venta de un escrito.<\/span><\/p>\n<p class=\"rtejustify\"><span style=\"font-size:14px;\">Saliendo de la rese\u00f1a del libro, si por un casual te decides por la autopublicaci\u00f3n, te voy a indicar un consejo. Cuando publiques un libro en plataformas digitales, no te recomiendo que publiques los mismos t\u00edtulos en las mismas plataformas, aunque parezca que haya mejor oferta de venta. En Espa\u00f1a, por ley, el precio de todos los libros debe ser el mismo en todos los puntos de venta. Si una plataforma decide bajar el precio de tu libro porque hace una oferta temporalmente, autom\u00e1ticamente bajar\u00e1 el precio en todas. Recibir\u00e1s avisos en el mejor de los casos, donde se te indicar\u00e1 que el libro ha bajado de precio.<\/span><\/p>\n<p class=\"rtejustify\"><a href=\"http:\/\/juanjobote.com\" target=\"_blank\"><span style=\"font-size: 14px;\">Juanjo Bot\u00e9<\/span><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mangas-Vega, Almudena. Autopublicar: los nuevos circuitos para autores e investigadores. Barcelona: UOC, 2016. 109 p&#8230;.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":0,"_seopress_analysis_target_kw":"","_seopress_news_disabled":"","_seopress_video_disabled":"","_seopress_video":[],"_seopress_pro_schemas_manual":[],"_seopress_pro_rich_snippets_disable_all":"","_seopress_pro_rich_snippets_disable":[],"_seopress_pro_schemas":[],"inline_featured_image":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[1400],"tags":[1133],"class_list":["post-3167","post","type-post","status-publish","format-standard","hentry","category-ressenyes","tag-llibres"],"acf":[],"taxonomy_info":{"category":[{"value":1400,"label":"Ressenyes"}],"post_tag":[{"value":1133,"label":"llibres"}]},"featured_image_src_large":false,"author_info":{"display_name":"jordi","author_link":"https:\/\/fima.ub.edu\/edl\/author\/jordi\/"},"comment_info":0,"category_info":[{"term_id":1400,"name":"Ressenyes","slug":"ressenyes","term_group":0,"term_taxonomy_id":1400,"taxonomy":"category","description":"","parent":0,"count":1345,"filter":"raw","cat_ID":1400,"category_count":1345,"category_description":"","cat_name":"Ressenyes","category_nicename":"ressenyes","category_parent":0}],"tag_info":[{"term_id":1133,"name":"llibres","slug":"llibres","term_group":0,"term_taxonomy_id":1133,"taxonomy":"post_tag","description":"","parent":0,"count":1214,"filter":"raw"}],"_links":{"self":[{"href":"https:\/\/fima.ub.edu\/edl\/wp-json\/wp\/v2\/posts\/3167","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fima.ub.edu\/edl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fima.ub.edu\/edl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fima.ub.edu\/edl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fima.ub.edu\/edl\/wp-json\/wp\/v2\/comments?post=3167"}],"version-history":[{"count":1,"href":"https:\/\/fima.ub.edu\/edl\/wp-json\/wp\/v2\/posts\/3167\/revisions"}],"predecessor-version":[{"id":4683,"href":"https:\/\/fima.ub.edu\/edl\/wp-json\/wp\/v2\/posts\/3167\/revisions\/4683"}],"wp:attachment":[{"href":"https:\/\/fima.ub.edu\/edl\/wp-json\/wp\/v2\/media?parent=3167"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fima.ub.edu\/edl\/wp-json\/wp\/v2\/categories?post=3167"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fima.ub.edu\/edl\/wp-json\/wp\/v2\/tags?post=3167"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}